{"id":186,"date":"2024-10-17T21:38:18","date_gmt":"2024-10-17T19:38:18","guid":{"rendered":"https:\/\/janexowoce.pl\/home-page\/"},"modified":"2025-11-14T12:07:18","modified_gmt":"2025-11-14T11:07:18","slug":"home-page","status":"publish","type":"page","link":"https:\/\/janexowoce.pl\/en\/","title":{"rendered":"Home page"},"content":{"rendered":"\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-e4fcl19\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-e4fcl19 \"><div class=\"eb-wrapper-outer eb-wrapper-e4fcl19\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-row alignfull freshgrains_banner  root-eb-row-4gqr3fa\"><div class=\"eb-parent-wrapper eb-parent-eb-row-4gqr3fa \"><div class=\"eb-row-root-container eb-row-4gqr3fa\" data-id=\"eb-row-4gqr3fa\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-hdszwcf\"><div class=\"eb-parent-wrapper eb-parent-eb-column-hdszwcf \"><div class=\"eb-column-wrapper eb-column-hdszwcf\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-advanced-image root-eb-advanced-image-phntw\"><div class=\"eb-parent-wrapper eb-parent-eb-advanced-image-phntw \"><figure class=\"eb-advanced-image-wrapper eb-advanced-image-phntw no-effect\" data-id=\"eb-advanced-image-phntw\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-img-style-rounded\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/home-bg-1.jpg\" alt=\"\"><\/div><\/div><\/figure><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-8vd9r6x\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-8vd9r6x \"><div class=\"eb-wrapper-outer eb-wrapper-8vd9r6x\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-e9kec6n\"><div class=\"eb-parent-wrapper eb-parent-eb-row-e9kec6n \"><div class=\"eb-row-root-container eb-row-e9kec6n\" data-id=\"eb-row-e9kec6n\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-5o9zgms\"><div class=\"eb-parent-wrapper eb-parent-eb-column-5o9zgms \"><div class=\"eb-column-wrapper eb-column-5o9zgms\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-advanced-image root-eb-advanced-image-ybsiva9\"><div class=\"eb-parent-wrapper eb-parent-eb-advanced-image-ybsiva9 eb_animation eb___animated eb___slideInLeft\"><figure class=\"eb-advanced-image-wrapper eb-advanced-image-ybsiva9 no-effect\" data-id=\"eb-advanced-image-ybsiva9\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-img-style-square\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/janex-owoce.svg\" alt=\"\"><\/div><\/div><\/figure><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-keutxkd\"><div class=\"eb-parent-wrapper eb-parent-eb-column-keutxkd \"><div class=\"eb-column-wrapper eb-column-keutxkd\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-wrapper  root-eb-wrapper-1fgbvj1\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-1fgbvj1 \"><div class=\"eb-wrapper-outer eb-wrapper-1fgbvj1\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-rpnmkyx\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-rpnmkyx eb_animation eb___animated eb___slideInRight\"><div class=\"eb-advance-heading-wrapper eb-advance-heading-rpnmkyx button-1 undefined\" data-id=\"eb-advance-heading-rpnmkyx\"><h2 class=\"eb-ah-title\"><span class=\"first-title\">Discover Janex Owoce<\/span><\/h2><p class=\"eb-ah-subtitle\">Janex Owoce Sp. z o.o. originated from a family business specializing in the wholesale of fruits and vegetables. The company is owned by Mr. Andrzej Zdzieszy\u0144ski and his two sons, Robert and Rafa\u0142. It has been operating on the market since 2002 and has been continuously developing since then. Over the years, operating under the name Janex S.C., the company expanded its infrastructure to provide suppliers with the best possible access to its services.    <\/p><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-pxm9f\"><div class=\"eb-parent-wrapper eb-parent-eb-row-pxm9f \"><div class=\"eb-row-root-container eb-row-pxm9f\" data-id=\"eb-row-pxm9f\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-yl47t\"><div class=\"eb-parent-wrapper eb-parent-eb-column-yl47t \"><div class=\"eb-column-wrapper eb-column-yl47t\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox root-eb-infobox-j9peq\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-j9peq eb_animation eb___animated eb___slideInLeft\"><div class=\"eb-infobox-j9peq eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/wholesale_15546746.svg\" alt=\"\"><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\"><strong>Fruit Purchasing and Storage<\/strong><\/h2><p class=\"description\">We specialize in the purchasing and professional storage of fruits, which allows us to maintain their freshness and quality until further processing or distribution<\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-ssvnz\"><div class=\"eb-parent-wrapper eb-parent-eb-column-ssvnz \"><div class=\"eb-column-wrapper eb-column-ssvnz\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox root-eb-infobox-iv5jq\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-iv5jq eb_animation eb___animated eb___zoomIn\"><div class=\"eb-infobox-iv5jq eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/agent_15546686.svg\" alt=\"\"><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\">Quality Control, Sorting, and Storage<\/h2><p class=\"description\">Our company offers comprehensive services in quality control, sorting, repackaging, and storage of goods returned to suppliers. We handle issues related to quality returns and more. <\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-bg49g\"><div class=\"eb-parent-wrapper eb-parent-eb-row-bg49g \"><div class=\"eb-row-root-container eb-row-bg49g\" data-id=\"eb-row-bg49g\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-sy2vg\"><div class=\"eb-parent-wrapper eb-parent-eb-column-sy2vg \"><div class=\"eb-column-wrapper eb-column-sy2vg\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox root-eb-infobox-e3ra0\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-e3ra0 eb_animation eb___animated eb___slideInLeft\"><div class=\"eb-infobox-e3ra0 eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/collaboration_10230376.svg\" alt=\"\"><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\"><strong>Cooperation with Processing Plants and Wholesale Buyers<\/strong><\/h2><p class=\"description\">We actively cooperate with fruit processing plants and wholesale buyers, ensuring a steady supply of industrial and fresh fruits for both domestic and international needs.<\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-bd62z\"><div class=\"eb-parent-wrapper eb-parent-eb-column-bd62z \"><div class=\"eb-column-wrapper eb-column-bd62z\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-infobox root-eb-infobox-3xddd\"><div class=\"eb-parent-wrapper eb-parent-eb-infobox-3xddd eb_animation eb___animated eb___zoomIn\"><div class=\"eb-infobox-3xddd eb-infobox-wrapper\"><div class=\"infobox-wrapper-inner\"><div class=\"icon-img-wrapper\"><div class=\"eb-infobox-image-wrapper\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-infobox-image\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/timetable_12302349.svg\" alt=\"\"><\/div><\/div><\/div><\/div><div class=\"contents-wrapper\"><h2 class=\"title\"><strong>Production Management and Seasonality<\/strong><\/h2><p class=\"description\">Efficient production management and a flexible approach to customers allow us to adapt to changing market conditions and ensure continuous deliveries despite the seasonal nature and availability of each product.<\/p><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-p21a5g5\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-p21a5g5 \"><div class=\"eb-wrapper-outer eb-wrapper-p21a5g5\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-mvhn7i7\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-mvhn7i7 eb_animation eb___animated eb___pulse\"><div class=\"eb-advance-heading-wrapper eb-advance-heading-mvhn7i7 button-1 undefined\" data-id=\"eb-advance-heading-mvhn7i7\"><h2 class=\"eb-ah-title\"><span class=\"first-title\">Business Profile<\/span><\/h2><p class=\"eb-ah-subtitle\">Our portfolio also includes other companies that operate successfully in the industry and complement our offer, providing top-quality products and services<\/p><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-e2qn1st\"><div class=\"eb-parent-wrapper eb-parent-eb-row-e2qn1st \"><div class=\"eb-row-root-container eb-row-e2qn1st\" data-id=\"eb-row-e2qn1st\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-ecs3ddh\"><div class=\"eb-parent-wrapper eb-parent-eb-column-ecs3ddh \"><div class=\"eb-column-wrapper eb-column-ecs3ddh\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-advanced-image root-eb-advanced-image-kci8qlm\"><div class=\"eb-parent-wrapper eb-parent-eb-advanced-image-kci8qlm eb_animation eb___animated eb___pulse\"><figure class=\"eb-advanced-image-wrapper eb-advanced-image-kci8qlm no-effect\" data-id=\"eb-advanced-image-kci8qlm\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-img-style-square\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/fresh-fruit-logo-dark.png\" alt=\"\"><\/div><a class=\"eb-image-link\" href=\"https:\/\/fresh-fruit.com.pl\/\" target=\"_self\"><\/a><\/div><\/figure><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-tzyfkkd\"><div class=\"eb-parent-wrapper eb-parent-eb-column-tzyfkkd \"><div class=\"eb-column-wrapper eb-column-tzyfkkd\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-advanced-image root-eb-advanced-image-344p8hr\"><div class=\"eb-parent-wrapper eb-parent-eb-advanced-image-344p8hr eb_animation eb___animated eb___pulse\"><figure class=\"eb-advanced-image-wrapper eb-advanced-image-344p8hr no-effect\" data-id=\"eb-advanced-image-344p8hr\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-img-style-square\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/logo-1.png\" alt=\"\"><\/div><a class=\"eb-image-link\" href=\"https:\/\/fhujanex.com\/\" target=\"_self\"><\/a><\/div><\/figure><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-xbc2v6m\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-xbc2v6m \"><div class=\"eb-wrapper-outer eb-wrapper-xbc2v6m\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-1aijwof\"><div class=\"eb-parent-wrapper eb-parent-eb-row-1aijwof \"><div class=\"eb-row-root-container eb-row-1aijwof\" data-id=\"eb-row-1aijwof\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-qk2casl\"><div class=\"eb-parent-wrapper eb-parent-eb-column-qk2casl \"><div class=\"eb-column-wrapper eb-column-qk2casl\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-advanced-heading  root-eb-advance-heading-8re7zfj\"><div class=\"eb-parent-wrapper eb-parent-eb-advance-heading-8re7zfj eb_animation eb___animated eb___slideInLeft\"><div class=\"eb-advance-heading-wrapper eb-advance-heading-8re7zfj button-1 undefined\" data-id=\"eb-advance-heading-8re7zfj\"><h2 class=\"eb-ah-title\"><span class=\"first-title\">We purchase <br\/>and supply<\/span><\/h2><p class=\"eb-ah-subtitle\">Fresh, top-quality fruits and vegetables directly from Polish farmers. We purchase and supply: apples, pears, strawberries, black and red currants, raspberries, peaches, sour cherries, sweet cherries, chokeberries, and plums &#8211; and more recently, also cauliflowers and broccoli. <\/p><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-m1u609w\"><div class=\"eb-parent-wrapper eb-parent-eb-column-m1u609w \"><div class=\"eb-column-wrapper eb-column-m1u609w\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-advanced-image root-eb-advanced-image-ucebeg8\"><div class=\"eb-parent-wrapper eb-parent-eb-advanced-image-ucebeg8 \"><figure class=\"eb-advanced-image-wrapper eb-advanced-image-ucebeg8 no-effect\" data-id=\"eb-advanced-image-ucebeg8\"><div class=\"eb-image-wrapper\"><div class=\"eb-image-wrapper-inner eb-img-style-rounded\"><img decoding=\"async\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/na-dloni.jpg\" alt=\"\"><\/div><\/div><\/figure><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"wp-block-essential-blocks-wrapper alignfull  root-eb-wrapper-i9lvxz6\"><div class=\"eb-parent-wrapper eb-parent-eb-wrapper-i9lvxz6 \"><div class=\"eb-wrapper-outer eb-wrapper-i9lvxz6\"><div class=\"eb-wrapper-inner\"><div class=\"eb-wrapper-inner-blocks eb-wrapper-align-center\">\n<div class=\"wp-block-essential-blocks-row alignfull  root-eb-row-a5q6j3o\"><div class=\"eb-parent-wrapper eb-parent-eb-row-a5q6j3o \"><div class=\"eb-row-root-container eb-row-a5q6j3o\" data-id=\"eb-row-a5q6j3o\"><div class=\"eb-row-wrapper\"><div class=\"eb-row-inner\">\n<div class=\"wp-block-essential-blocks-column  root-eb-column-sc9qraz\"><div class=\"eb-parent-wrapper eb-parent-eb-column-sc9qraz \"><div class=\"eb-column-wrapper eb-column-sc9qraz\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-number-counter root-eb-counter-b5973h6\"><div class=\"eb-parent-wrapper eb-parent-eb-counter-b5973h6 eb_animation eb___animated eb___slideInLeft\"><div class=\"eb-counter-b5973h6 eb-counter-wrapper\"><div class=\"icon-img-wrapper\"><div class=\"eb-counter-image-wrapper\"><img decoding=\"async\" class=\"eb-counter-image\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/orange_6944318.svg\"><\/div><\/div><div class=\"counter-contents-wrapper\"><h4 class=\"eb-counter-number\"><span class=\"eb-counter-prefix\"><\/span><span class=\"eb-counter eb-counter-number\" data-duration=\"1000\" data-startvalue=\"0\" data-target=\"100000\" data-separator=\",\" data-isshowseparator=\"false\">0<\/span><span class=\"eb-counter-suffix\">+<\/span><\/h4><h3 class=\"eb-counter-title\">Processed<br>tons of fruit<\/h3><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-9nwjam1\"><div class=\"eb-parent-wrapper eb-parent-eb-column-9nwjam1 \"><div class=\"eb-column-wrapper eb-column-9nwjam1\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-number-counter root-eb-counter-dgoawvn\"><div class=\"eb-parent-wrapper eb-parent-eb-counter-dgoawvn eb_animation eb___animated eb___zoomIn\"><div class=\"eb-counter-dgoawvn eb-counter-wrapper\"><div class=\"icon-img-wrapper\"><div class=\"eb-counter-image-wrapper\"><img decoding=\"async\" class=\"eb-counter-image\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/crops_5609046.svg\"><\/div><\/div><div class=\"counter-contents-wrapper\"><h4 class=\"eb-counter-number\"><span class=\"eb-counter-prefix\"><\/span><span class=\"eb-counter eb-counter-number\" data-duration=\"1000\" data-startvalue=\"0\" data-target=\"300\" data-separator=\",\" data-isshowseparator=\"false\">0<\/span><span class=\"eb-counter-suffix\">+<\/span><\/h4><h3 class=\"eb-counter-title\">Cooperating<br>orchards<\/h3><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-column  root-eb-column-32shap6\"><div class=\"eb-parent-wrapper eb-parent-eb-column-32shap6 \"><div class=\"eb-column-wrapper eb-column-32shap6\"><div class=\"eb-column-inner\">\n<div class=\"wp-block-essential-blocks-number-counter root-eb-counter-obqa992\"><div class=\"eb-parent-wrapper eb-parent-eb-counter-obqa992 eb_animation eb___animated eb___slideInRight\"><div class=\"eb-counter-obqa992 eb-counter-wrapper\"><div class=\"icon-img-wrapper\"><div class=\"eb-counter-image-wrapper\"><img decoding=\"async\" class=\"eb-counter-image\" src=\"https:\/\/janexowoce.pl\/wp-content\/uploads\/2024\/10\/delivery-truck_3368199.svg\"><\/div><\/div><div class=\"counter-contents-wrapper\"><h4 class=\"eb-counter-number\"><span class=\"eb-counter-prefix\"><\/span><span class=\"eb-counter eb-counter-number\" data-duration=\"1000\" data-startvalue=\"0\" data-target=\"150\" data-separator=\",\" data-isshowseparator=\"false\">0<\/span><span class=\"eb-counter-suffix\">+<\/span><\/h4><h3 class=\"eb-counter-title\">Cooperating<br>customers<\/h3><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templately_header_footer","meta":{"_eb_attr":"","inline_featured_image":false,"footnotes":""},"class_list":["post-186","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/janexowoce.pl\/en\/wp-json\/wp\/v2\/pages\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/janexowoce.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/janexowoce.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/janexowoce.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/janexowoce.pl\/en\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":4,"href":"https:\/\/janexowoce.pl\/en\/wp-json\/wp\/v2\/pages\/186\/revisions"}],"predecessor-version":[{"id":242,"href":"https:\/\/janexowoce.pl\/en\/wp-json\/wp\/v2\/pages\/186\/revisions\/242"}],"wp:attachment":[{"href":"https:\/\/janexowoce.pl\/en\/wp-json\/wp\/v2\/media?parent=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}